{"id":2041,"date":"2022-03-11T11:38:26","date_gmt":"2022-03-11T09:38:26","guid":{"rendered":"https:\/\/aitanatop.ific.uv.es\/aitanatop\/?p=2041"},"modified":"2023-12-21T21:40:28","modified_gmt":"2023-12-21T19:40:28","slug":"mbmh","status":"publish","type":"post","link":"https:\/\/aitanatop.ific.uv.es\/aitanatop\/mbmh\/","title":{"rendered":"\u00bfPor qu\u00e9 las masas de las part\u00edculas fundamentales no son invariables?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2041\" class=\"elementor elementor-2041\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-39ad1a6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"39ad1a6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9e31c88\" data-id=\"9e31c88\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-14b7b59 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"14b7b59\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2cc0882\" data-id=\"2cc0882\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b4531bf elementor-widget elementor-widget-spacer\" data-id=\"b4531bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0fe0cbb elementor-widget elementor-widget-heading\" data-id=\"0fe0cbb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">\u00bfPor qu\u00e9 las masas de las part\u00edculas elementales no son invariables?<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a19420f elementor-widget elementor-widget-heading\" data-id=\"a19420f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Investigadores del IFIC, en colaboraci\u00f3n con investigadores de las Universidades de Viena y Tohoku y el Instituto Paul Scherrer, miden por primera vez la masa del quark bottom a partir de sus interacciones con el bos\u00f3n de Higgs y confirman, como predice la teor\u00eda, que no es una cantidad invariable.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8fc8840 elementor-widget elementor-widget-image\" data-id=\"8fc8840\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1370\" height=\"3\" src=\"https:\/\/aitanatop.ific.uv.es\/aitanatop\/wp-content\/uploads\/2021\/05\/Separador.png\" class=\"attachment-full size-full wp-image-135\" alt=\"\" srcset=\"https:\/\/aitanatop.ific.uv.es\/aitanatop\/wp-content\/uploads\/2021\/05\/Separador.png 1370w, https:\/\/aitanatop.ific.uv.es\/aitanatop\/wp-content\/uploads\/2021\/05\/Separador-300x1.png 300w, https:\/\/aitanatop.ific.uv.es\/aitanatop\/wp-content\/uploads\/2021\/05\/Separador-1024x2.png 1024w, https:\/\/aitanatop.ific.uv.es\/aitanatop\/wp-content\/uploads\/2021\/05\/Separador-768x2.png 768w\" sizes=\"(max-width: 1370px) 100vw, 1370px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98ab847 elementor-widget elementor-widget-button\" data-id=\"98ab847\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/aitanatop.ific.uv.es\/aitanatop\/mb-mh-english\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Click here for the english version<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d198d5 elementor-widget elementor-widget-text-editor\" data-id=\"5d198d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En f\u00edsica, la masa y el peso de un objeto representan dos conceptos esencialmente diferentes. La masa de un objeto es una medida de la cantidad de materia que contiene, a diferencia del peso, que es una medida de la fuerza gravitatoria a la que est\u00e1 sometido. Seg\u00fan las leyes de Newton, esa fuerza gravitatoria o peso es proporcional a la masa, por lo que ambos conceptos suelen utilizarse indistintamente, aunque de forma inapropiada, en el lenguaje coloquial.<\/p><p>Un objeto a nivel del mar es ligeramente menos pesado en la cima del Everest porque est\u00e1 m\u00e1s alejado del centro de la Tierra, lo suficiente para que la intensidad de la gravedad sea ligeramente m\u00e1s d\u00e9bil. En la superficie de la Luna, donde la intensidad de la fuerza gravitatoria es seis veces menor que en la Tierra, su peso es, en consecuencia, seis veces menor. Su masa, en cambio, es una cantidad invariable, caracter\u00edstica del objeto e independiente del lugar en el que se encuentre. Para ser precisos, en lugar de preguntar \u201c\u00bfcu\u00e1nto peso?\u201d, deber\u00edamos plantear siempre la pregunta \u201c\u00bfcu\u00e1l es mi masa?\u201d.<\/p><p>En el mundo microsc\u00f3pico ocurre algo similar. Aunque la fuerza de la gravedad no suele ser relevante entre las part\u00edculas elementales, \u00e9stas se encuentran sometidas a otras fuerzas fundamentales como la fuerza fuerte, la d\u00e9bil y la electromagn\u00e9tica, y la intensidad de todas estas fuerzas no siempre es la misma, sino que depende en gran medida de la energ\u00eda a la que las part\u00edculas elementales se aceleran y colisionan entre s\u00ed.<\/p><p>Lo extraordinario en este caso es que debido a las leyes cu\u00e1nticas que gobiernan el microcosmos, las masas de las part\u00edculas elementales dejan tambi\u00e9n de ser una cantidad intr\u00ednseca inmutable. Esa variabilidad, sin embargo, no es arbitraria. Aunque la teor\u00eda llamada Modelo Est\u00e1ndar no puede predecir el valor de las masas de las part\u00edculas elementales ni la intensidad de las fuerzas fundamentales, s\u00ed predice con gran precisi\u00f3n c\u00f3mo cambian en funci\u00f3n de la energ\u00eda. Es decir, midiendo las masas e intensidades de las fuerzas en un experimento a una energ\u00eda de referencia, podemos predecir cuales ser\u00e1n sus valores en otro experimento donde las part\u00edculas interaccionen a una energ\u00eda diferente.<\/p><p>Esa variabilidad viene determinada por las fluctuaciones cu\u00e1nticas del vac\u00edo permitidas por la teor\u00eda. Estas fluctuaciones generan a partir del vac\u00edo part\u00edculas virtuales que aparecen y desaparecen afectando a la masa y a la intensidad de las fuerzas en funci\u00f3n de la distancia, o equivalentemente energ\u00eda, a la que observamos la part\u00edcula. Los llamados quarks deber\u00edan ser, seg\u00fan el Modelo Est\u00e1ndar, cada vez m\u00e1s ligeros a medida que realizamos experimentos a energ\u00edas m\u00e1s altas. En cambio, el bos\u00f3n de Higgs y los leptones, como los electrones y muones, ser\u00edan m\u00e1s masivos.<\/p><p>Demostrar que las masas de las part\u00edculas elementales cambian en funci\u00f3n de la energ\u00eda del experimento es, en primer lugar, una prueba clara de su comportamiento cu\u00e1ntico. Medir adem\u00e1s ese cambio con gran precisi\u00f3n permite, por un lado, someter a un test de estr\u00e9s la validez de las predicciones del Modelo Est\u00e1ndar y, por otro, intuir la posible existencia de nuevas part\u00edculas o fuerzas en caso de que los datos se desv\u00eden de la evoluci\u00f3n esperada.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5a4484 elementor-widget elementor-widget-text-editor\" data-id=\"e5a4484\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La primera demostraci\u00f3n de la variabilidad de la masa de un quark fue realizada a partir de datos de LEP, el predecesor del Gran Colisionador de Hadrones (LHC) del CERN, por investigadores del IFIC, centro mixto del CSIC y la Universidad de Valencia. Este trabajo, en el que colaboraron estrechamente investigadores te\u00f3ricos y experimentales del IFIC, logr\u00f3 demostrar que el quark bottom era un 40% m\u00e1s ligero en LEP que en otros experimentos realizados a energ\u00edas m\u00e1s bajas.<\/p><blockquote><h3 style=\"text-align: right\"><span style=\"color: #2d418e\"><em><strong>Las fluctuaciones cu\u00e1nticas del vac\u00edo son las responsables de que las masas de las part\u00edculas elementales no sean invariables<\/strong><\/em><\/span> <\/h3><\/blockquote>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bbda63d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bbda63d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-836156c\" data-id=\"836156c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a4fec75 elementor-widget elementor-widget-spacer\" data-id=\"a4fec75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a007e27 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a007e27\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-63c5739\" data-id=\"63c5739\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50df955 elementor-widget elementor-widget-image\" data-id=\"50df955\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"709\" height=\"708\" src=\"https:\/\/aitanatop.ific.uv.es\/aitanatop\/wp-content\/uploads\/2022\/03\/mbmH.jpg\" class=\"attachment-large size-large wp-image-2043\" alt=\"\" srcset=\"https:\/\/aitanatop.ific.uv.es\/aitanatop\/wp-content\/uploads\/2022\/03\/mbmH.jpg 709w, https:\/\/aitanatop.ific.uv.es\/aitanatop\/wp-content\/uploads\/2022\/03\/mbmH-300x300.jpg 300w, https:\/\/aitanatop.ific.uv.es\/aitanatop\/wp-content\/uploads\/2022\/03\/mbmH-150x150.jpg 150w\" sizes=\"(max-width: 709px) 100vw, 709px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dac6dc7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dac6dc7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f464ea7\" data-id=\"f464ea7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-99c893b elementor-widget elementor-widget-text-editor\" data-id=\"99c893b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El descubrimiento del bos\u00f3n de Higgs y la observaci\u00f3n de la desintegraci\u00f3n del bos\u00f3n de Higgs en pares formados por un quark bottom y su antipart\u00edcula en el LHC permiten una medici\u00f3n completamente nueva de la masa del quark bottom a una energ\u00eda superior. Para ello, investigadores del IFIC, en colaboraci\u00f3n con investigadores de las universidades de Viena y Tohoku y el Instituto Paul Scherzer pr\u00f3ximo a Z\u00fcrich, han utilizado las predicciones te\u00f3ricas m\u00e1s avanzadas conocidas hasta ahora.<\/p><p>El trabajo ha sido publicado en Physical Review Letters, donde los investigadores han presentado una nueva medida de la masa del quark bottom con una precisi\u00f3n del 14%. El valor obtenido es compatible con las predicciones del Modelo Est\u00e1ndar y descarta la hip\u00f3tesis de invariabilidad con una significancia estad\u00edstica de casi 7 desviaciones est\u00e1ndar. En f\u00edsica de part\u00edculas se requieren al menos 5 desviaciones est\u00e1ndar para que un resultado sea considerado consolidado. Los resultados presentados son la primera medida de la masa del quark bottom a la escala de energ\u00edas equivalente a la masa del bos\u00f3n de Higgs, que es 40 veces superior a la propia masa del quark, y refuerzan todav\u00eda m\u00e1s la evidencia sobre su evoluci\u00f3n originada por los procesos cu\u00e1nticos que ocurren a escala microsc\u00f3pica.<\/p><p>El trabajo incluye tambi\u00e9n un estudio prospectivo sobre las mejoras que podr\u00edan obtenerse en la nueva fase de adquisici\u00f3n de datos del LHC que est\u00e1 a punto de comenzar, as\u00ed como de los datos de futuros aceleradores como el Colisionador Lineal Internacional (ILC).<\/p><p style=\"text-align: right;\"><em>Pieza escrita<\/em><em> por<\/em> <strong><em><a href=\"https:\/\/webific.ific.uv.es\/web\/content\/rodrigo-garc%C3%ADa-germ%C3%A1n\">G. Rodrigo<\/a><\/em><\/strong><\/p><hr \/><p style=\"text-align: center;\"><strong>Referencia<\/strong><\/p><p style=\"text-align: center;\">J. Aparisi, J. Fuster, A. Hoang, A. Irles, C. Lepenik, G. Rodrigo, M. Spira, S. Tairafune, M. Vos, H. Yamamoto and R. Yonamine,<\/p><p style=\"text-align: center;\">mb at mH: the running bottom quark mass and the Higgs boson, Phys. Rev. Lett. 128, 122001. DOI: <a href=\"https:\/\/doi.org\/10.1103\/PhysRevLett.128.122001\">https:\/\/doi.org\/10.1103\/PhysRevLett.128.122001<\/a><\/p><p style=\"text-align: center;\">\u00a0<\/p><p style=\"text-align: center;\">\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00bfPor qu\u00e9 las masas de las part\u00edculas elementales no son invariables? Investigadores del IFIC, en colaboraci\u00f3n con investigadores de las Universidades de Viena y Tohoku y el Instituto Paul Scherrer, miden por primera vez la masa del quark bottom a partir de sus interacciones con el bos\u00f3n de Higgs y confirman, como predice la teor\u00eda, [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":2049,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[15],"tags":[47,36,43,51,50,48,49,41,45,42,46,44],"class_list":["post-2041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-milestones","tag-bottom-quark","tag-experiment","tag-higgs","tag-higgs-factories","tag-ilc","tag-lhc","tag-llep","tag-mass","tag-physics-review-letters","tag-quantum-physics","tag-quark","tag-standard-model","wpbf-post"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/aitanatop.ific.uv.es\/aitanatop\/wp-content\/uploads\/2022\/03\/quark-2.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/aitanatop.ific.uv.es\/aitanatop\/wp-json\/wp\/v2\/posts\/2041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aitanatop.ific.uv.es\/aitanatop\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aitanatop.ific.uv.es\/aitanatop\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aitanatop.ific.uv.es\/aitanatop\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/aitanatop.ific.uv.es\/aitanatop\/wp-json\/wp\/v2\/comments?post=2041"}],"version-history":[{"count":0,"href":"https:\/\/aitanatop.ific.uv.es\/aitanatop\/wp-json\/wp\/v2\/posts\/2041\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aitanatop.ific.uv.es\/aitanatop\/wp-json\/wp\/v2\/media\/2049"}],"wp:attachment":[{"href":"https:\/\/aitanatop.ific.uv.es\/aitanatop\/wp-json\/wp\/v2\/media?parent=2041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aitanatop.ific.uv.es\/aitanatop\/wp-json\/wp\/v2\/categories?post=2041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aitanatop.ific.uv.es\/aitanatop\/wp-json\/wp\/v2\/tags?post=2041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}